{"id":2732,"date":"2019-01-09T16:45:03","date_gmt":"2019-01-09T15:45:03","guid":{"rendered":"https:\/\/salernomobilita.grupposistemisalerno.it\/?page_id=2732"},"modified":"2025-06-09T16:07:46","modified_gmt":"2025-06-09T14:07:46","slug":"trasparenza","status":"publish","type":"page","link":"https:\/\/salernomobilita.grupposistemisalerno.it\/index.php\/trasparenza\/","title":{"rendered":"Societ\u00e0 Trasparente fino al 31 dicembre 2024"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" id=\"iframetrasparenza\" style=\"width: 100%; height: 5000px; visibility: visible;\" src=\"https:\/\/sm.pdt.applicazioni.trecentosoftware.it\/web\/Views\/Templated\/RootMenuPage.aspx?Page=1\" name=\" iframetrasparenza \" width=\"100%\" height=\"981\" scrolling=\"yes\" allowfullscreen=\"allowfullscreen\"><br \/>\n<\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-nosidebar.php","meta":{"footnotes":""},"tags":[],"class_list":["post-2732","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/salernomobilita.grupposistemisalerno.it\/index.php\/wp-json\/wp\/v2\/pages\/2732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/salernomobilita.grupposistemisalerno.it\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/salernomobilita.grupposistemisalerno.it\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/salernomobilita.grupposistemisalerno.it\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/salernomobilita.grupposistemisalerno.it\/index.php\/wp-json\/wp\/v2\/comments?post=2732"}],"version-history":[{"count":15,"href":"https:\/\/salernomobilita.grupposistemisalerno.it\/index.php\/wp-json\/wp\/v2\/pages\/2732\/revisions"}],"predecessor-version":[{"id":4318,"href":"https:\/\/salernomobilita.grupposistemisalerno.it\/index.php\/wp-json\/wp\/v2\/pages\/2732\/revisions\/4318"}],"wp:attachment":[{"href":"https:\/\/salernomobilita.grupposistemisalerno.it\/index.php\/wp-json\/wp\/v2\/media?parent=2732"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/salernomobilita.grupposistemisalerno.it\/index.php\/wp-json\/wp\/v2\/tags?post=2732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}